{"id":1737,"date":"2020-02-20T15:32:36","date_gmt":"2020-02-20T14:32:36","guid":{"rendered":"http:\/\/www.grupodcc3000.com\/asociado\/construferro\/2020\/02\/20\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/"},"modified":"2020-02-20T15:32:36","modified_gmt":"2020-02-20T14:32:36","slug":"fibratec-v-12-frente-a-otras-fibras-de-hormigon","status":"publish","type":"post","link":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/","title":{"rendered":"FIBRATEC V-12 frente a otras fibras de hormig\u00f3n"},"content":{"rendered":"\n<p>Hoy venimos a hablaros de las fibras de hormig\u00f3n. Cuando se habla sobre las fibras para hormig\u00f3n nos encontramos con muchas opciones en el mercado. Estas son algunas de las ventajas de esta fibra tal y como nos cuentan en la web de <strong><a href=\"https:\/\/www.fibratec.eu\/\">Fibratec<\/a><\/strong>: <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">&nbsp;VENTAJAS:<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Debido a su peso espec\u00edfico muy pr\u00f3ximo al del hormig\u00f3n (2,68 kg\/dm\u00b3) y su ensimaje (recubrimiento) patentado para favorecer su distribuci\u00f3n, nuestra fibra para hormig\u00f3n V12-AM se mezcla de forma totalmente homog\u00e9nea en tiempo r\u00e9cord. (Entre 1 y 13 minutos en funci\u00f3n del tama\u00f1o de la cuba de mezclado. Entre 100 litros y 10m\u00b3 respectivamente).<\/li><li>La fibra es totalmente invisible en superficie, permitiendo suelos acabados en pulido o impreso.<\/li><li>Es compatible con cualquier aditivo para hormig\u00f3n ya sea alcalino o \u00e1cido, tintes, acelerantes, retardantes\u2026 TODOS LOS ADITIVOS, ya que es totalmente inerte.<\/li><li>Su resistencia a rotura por tracci\u00f3n es superior a la de las fibras de acero (1620 N\/mm\u00b2 vs 1200 N\/mm\u00b2)<\/li><li>No requiere adici\u00f3n de agua ni superfluidificante.<\/li><li>Ahorra gran espacio de almacenamiento debido a su gran rendimiento. De media, 2 kg de Fibratec V12-AM que caben en una caja de zapatos equivale a una malla electrosoldada (mallazo) de 13m\u00b2 de cualquier di\u00e1metro.<\/li><li>Permite sustituir mallas electrosoldadas (mallazos) en soleras peatonales con tan solo 1 kg\/m\u00b3.<\/li><li>Permite sustituir mallas electrosoldadas (mallazos) en soleras de parking e industriales con 2 kg\/m\u00b3.<\/li><li>Con 3 kg\/m\u00b3 se resuelven la mayor\u00eda de las soleras de mayores exigencias de cargas puntuales grandes.<\/li><li>Ahorro de tiempo y dinero ya que: No requiere cortar, adecuar, solapar ni calzar mallas electrosoldadas gracias a las fibras para hormig\u00f3n&nbsp;Fibratec V12-AM.<\/li><\/ul>\n\n\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/F-53pu9FFcI\" allowfullscreen=\"allowfullscreen\" width=\"100%\" height=\"100%\" frameborder=\"0\"><\/iframe><\/p>\n\n\n<p>Ponte en contacto con nosotros y te asesoraremos de la mejor manera para que el acabado de tu obra sea lo m\u00e1s profesional posible. <\/p>\n\n\n\n<p>\ud83d\udce7&nbsp;info@grupodcc3000.com<br>\u27a1\ufe0fGrupo DCC 3000<br>\ud83c\udf10<a href=\"https:\/\/l.facebook.com\/l.php?u=http%3A%2F%2Fwww.grupodcc3000.com%2F%3Ffbclid%3DIwAR1-P2uSaHb75oy1LkktEOD6PsfjHoo05jgHh2XLVZ42z092eE9J7CEKVq0&amp;h=AT19A-obTf-A5xz4PYm0-7IWoGV4G5tScWiYuAebOE-75UyIVTzBgBAc0tcY2EC_Tn1FsSNYMEiwkGJNBE8ce8QZtCvH6a3tcKM2vGzktnrJSGiBIJ-GZag2SYLEsjENmDUJsPxhSI9nPUQctF1r0BWZqBXah2T4AyMfB5VpOM8vaIHwLyFgVsDBkzTi3IHqNsCXrx6jhrEZ8qKTr1_BeIGxG4fFTp1pXVXi-wod09U7TIB7DMDH0ThyrFFLxCwBokozSjKEOf4hZ5KPNYTRCngnJYWNpPH0n2hastkEt9r8yNhaknMpBWItS618zk_HlvTFWyXmPS-Z3nSTvigzD2bVi-HC-KfqHD-du6XSqVgCRNMre6bOwvfRG_vmQGeauMzRj6_DSA-NkGUfPpAkz_9cOJuy-nEIThpTSPw3pp84NrnzHq9TEnD3heChojUydGHyn3UTp27ehPTvO_Z20Qg5dL99O26v8K3wpkft11LFqmoBBvuGjg2U2avA-Tc2Ex6dpoM-MvOJHusTyjoJOb1CqfqtMbIl17A7XzlidLbHBdluZFCWVFg-XY1-F8bBFX6ngyxliAKA-tjBPj8a1GRYkKEFft0tE_6g-Y3UAWlP5xNXwtDd_qlpe1yZAfS8O4Al9Uo\" target=\"_blank\" rel=\"noreferrer noopener\">www.grupodcc3000.com<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy venimos a hablaros de las fibras de hormig\u00f3n. <\/p>\n<p>Cuando se habla sobre las fibras para hormig\u00f3n nos encontramos con muchas opciones en el mercado. <\/p>\n<p>Estas son algunas de las ventajas de esta fibra tal y como nos cuentan en la web de Fibratec: <\/p>\n<p>\ud83d\udce7 info@grupodcc3000.com<br \/>\n\u27a1\ufe0fGrupo DCC 3000<br \/>\n\ud83c\udf10www.grupodcc3000.com<\/p>\n","protected":false},"author":4,"featured_media":1738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FIBRATEC V-12 frente a otras fibras de hormig\u00f3n - Materiales Construcci\u00f3n Construferro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FIBRATEC V-12 frente a otras fibras de hormig\u00f3n - Materiales Construcci\u00f3n Construferro\" \/>\n<meta property=\"og:description\" content=\"Hoy venimos a hablaros de las fibras de hormig\u00f3n.  Cuando se habla sobre las fibras para hormig\u00f3n nos encontramos con muchas opciones en el mercado.  Estas son algunas de las ventajas de esta fibra tal y como nos cuentan en la web de Fibratec:  \ud83d\udce7 info@grupodcc3000.com \u27a1\ufe0fGrupo DCC 3000 \ud83c\udf10www.grupodcc3000.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/\" \/>\n<meta property=\"og:site_name\" content=\"Materiales Construcci\u00f3n Construferro\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-20T14:32:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-content\/uploads\/sites\/56\/2020\/02\/Degradacion-fibra-sin-zirconio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"410\" \/>\n\t<meta property=\"og:image:height\" content=\"279\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"asociados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"asociados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/\"},\"author\":{\"name\":\"asociados\",\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119\"},\"headline\":\"FIBRATEC V-12 frente a otras fibras de hormig\u00f3n\",\"datePublished\":\"2020-02-20T14:32:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/\"},\"wordCount\":328,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-content\/uploads\/sites\/56\/2020\/02\/Degradacion-fibra-sin-zirconio.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/\",\"url\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/\",\"name\":\"FIBRATEC V-12 frente a otras fibras de hormig\u00f3n - Materiales Construcci\u00f3n Construferro\",\"isPartOf\":{\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-content\/uploads\/sites\/56\/2020\/02\/Degradacion-fibra-sin-zirconio.jpg\",\"datePublished\":\"2020-02-20T14:32:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#primaryimage\",\"url\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-content\/uploads\/sites\/56\/2020\/02\/Degradacion-fibra-sin-zirconio.jpg\",\"contentUrl\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-content\/uploads\/sites\/56\/2020\/02\/Degradacion-fibra-sin-zirconio.jpg\",\"width\":410,\"height\":279},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FIBRATEC V-12 frente a otras fibras de hormig\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/#website\",\"url\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/\",\"name\":\"Materiales Construcci\u00f3n Construferro\",\"description\":\"Otro sitio m\u00e1s de Asociados GrupoDCC3000\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119\",\"name\":\"asociados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"caption\":\"asociados\"},\"url\":\"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/author\/asociados\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FIBRATEC V-12 frente a otras fibras de hormig\u00f3n - Materiales Construcci\u00f3n Construferro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/","og_locale":"es_ES","og_type":"article","og_title":"FIBRATEC V-12 frente a otras fibras de hormig\u00f3n - Materiales Construcci\u00f3n Construferro","og_description":"Hoy venimos a hablaros de las fibras de hormig\u00f3n.  Cuando se habla sobre las fibras para hormig\u00f3n nos encontramos con muchas opciones en el mercado.  Estas son algunas de las ventajas de esta fibra tal y como nos cuentan en la web de Fibratec:  \ud83d\udce7 info@grupodcc3000.com \u27a1\ufe0fGrupo DCC 3000 \ud83c\udf10www.grupodcc3000.com","og_url":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/","og_site_name":"Materiales Construcci\u00f3n Construferro","article_published_time":"2020-02-20T14:32:36+00:00","og_image":[{"width":410,"height":279,"url":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-content\/uploads\/sites\/56\/2020\/02\/Degradacion-fibra-sin-zirconio.jpg","type":"image\/jpeg"}],"author":"asociados","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"asociados","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#article","isPartOf":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/"},"author":{"name":"asociados","@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119"},"headline":"FIBRATEC V-12 frente a otras fibras de hormig\u00f3n","datePublished":"2020-02-20T14:32:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/"},"wordCount":328,"commentCount":0,"image":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-content\/uploads\/sites\/56\/2020\/02\/Degradacion-fibra-sin-zirconio.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/","url":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/","name":"FIBRATEC V-12 frente a otras fibras de hormig\u00f3n - Materiales Construcci\u00f3n Construferro","isPartOf":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#primaryimage"},"image":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-content\/uploads\/sites\/56\/2020\/02\/Degradacion-fibra-sin-zirconio.jpg","datePublished":"2020-02-20T14:32:36+00:00","author":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119"},"breadcrumb":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#primaryimage","url":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-content\/uploads\/sites\/56\/2020\/02\/Degradacion-fibra-sin-zirconio.jpg","contentUrl":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-content\/uploads\/sites\/56\/2020\/02\/Degradacion-fibra-sin-zirconio.jpg","width":410,"height":279},{"@type":"BreadcrumbList","@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/fibratec-v-12-frente-a-otras-fibras-de-hormigon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/"},{"@type":"ListItem","position":2,"name":"FIBRATEC V-12 frente a otras fibras de hormig\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/#website","url":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/","name":"Materiales Construcci\u00f3n Construferro","description":"Otro sitio m\u00e1s de Asociados GrupoDCC3000","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119","name":"asociados","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","caption":"asociados"},"url":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/author\/asociados\/"}]}},"_links":{"self":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-json\/wp\/v2\/posts\/1737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-json\/wp\/v2\/comments?post=1737"}],"version-history":[{"count":0,"href":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-json\/wp\/v2\/posts\/1737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-json\/wp\/v2\/media\/1738"}],"wp:attachment":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-json\/wp\/v2\/media?parent=1737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-json\/wp\/v2\/categories?post=1737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/construferro\/wp-json\/wp\/v2\/tags?post=1737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}