{"id":1445,"date":"2019-07-26T10:40:18","date_gmt":"2019-07-26T10:40:18","guid":{"rendered":"https:\/\/www.grupodcc3000.com\/asociado\/?p=1445"},"modified":"2019-07-26T10:40:18","modified_gmt":"2019-07-26T10:40:18","slug":"el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad","status":"publish","type":"post","link":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/","title":{"rendered":"El parquet, un tipo de suelo que no pierde popularidad"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.grupodcc3000.com\/asociado\/wp-content\/uploads\/2019\/07\/salon-abierto-al-dormitorio-pared-cristal.jpg\" alt=\"\" class=\"wp-image-1398\" srcset=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/07\/salon-abierto-al-dormitorio-pared-cristal.jpg 800w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/07\/salon-abierto-al-dormitorio-pared-cristal-300x200.jpg 300w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/07\/salon-abierto-al-dormitorio-pared-cristal-768x512.jpg 768w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/07\/salon-abierto-al-dormitorio-pared-cristal-480x320.jpg 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n<h3 class=\"wp-block-heading\">Pese a la irrupci\u00f3n de otras tendencias en suelos, la madera sigue siendo una apuesta segura para los que buscan una combinaci\u00f3n especial en su vivienda.<\/h3>\n\n\n<p class=\"wp-block-paragraph\">En cualquier \u00e9poca del a\u00f1o, nos planteamos realizar algunos cambios en nuestra casa. El parquet es uno de los materiales m\u00e1s aclamados y utilizados para construir los suelos de muchas viviendas. En este post te mostramos algunos beneficios que aporta este material. <\/p>\n\n\n<h2 class=\"wp-block-heading\">Limpieza f\u00e1cil<\/h2>\n\n\n<p class=\"wp-block-paragraph\">El parquet es f\u00e1cil de limpiar y tambi\u00e9n de mantener, ya que casi no acumula moho, \u00e1caros de polvo o cualquier elemento alerg\u00e9nico, por lo que adem\u00e1s suelen ser ideales para las personas con alergias. Con un cuidado sencillo podr\u00e1 lucir como nuevo en tu casa.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Durabilidad<\/h2>\n\n\n<p class=\"wp-block-paragraph\">Los suelos de parquet suelen ser muy duraderos, ya que la madera es un material longevo que se conserva bien. Adem\u00e1s, teniendo que mientras m\u00e1s grueso sea el suelo mayor ser\u00e1 su durabilidad, te recomendamos buscar un parquet muy grueso.<\/p>\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.elmueble.com\/medio\/2018\/12\/18\/salon-desde-recibidor-con-suelo-de-madera_dfc97162_600x600.jpg\" alt=\"Resultado de imagen de parquet ambientes\" \/><figcaption>El Mueble<\/figcaption><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">Aislante natural<\/h2>\n\n\n<p class=\"wp-block-paragraph\">Otro beneficio a tener en cuenta de este material es su capacidad como aislante natural. La madera es un excelente aislante del fr\u00edo lo que nos permitir\u00e1 mantener la buena temperatura en las \u00e9pocas invernales; Adem\u00e1s, tambi\u00e9n es un aislante perfecto del calor, lo que tambi\u00e9n garantiza la comodidad en las estaciones de m\u00e1s temperatura. <\/p>\n\n\n<h2 class=\"wp-block-heading\">Est\u00e9tico<\/h2>\n\n\n<p class=\"wp-block-paragraph\">La madera transmite un estilo propio, una apariencia r\u00fastica y campestre. Adem\u00e1s, combina de forma ideal con pr\u00e1cticamente todo tipo de materiales, lo que lo convierte en el complemento perfecto para la decoraci\u00f3n de cualquier vivienda. <\/p>\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/reforcan.es\/wp-content\/uploads\/2015\/02\/parquet-merbau-multicapa-3562-1811853-1000x500.jpg\" alt=\"Resultado de imagen de parquet ambientes\" \/><figcaption>Reforcan<\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">En el Grupo DCC 3000 tenemos un proveedor experto en este material de construcci\u00f3n: <a href=\"https:\/\/www.kronotex.com\/laminado-0230334552.html?SID=X32Bf1D69bcf\">Kronotex<\/a>. No obstante, si tienes cualquier duda, cons\u00faltanos por estos y otros productos de la marca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La madera sigue siendo una apuesta segura para los que buscan una combinaci\u00f3n especial en su vivienda.<\/p>\n","protected":false},"author":4,"featured_media":1398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El parquet, un tipo de suelo que no pierde popularidad - pedroriosehijos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El parquet, un tipo de suelo que no pierde popularidad - pedroriosehijos\" \/>\n<meta property=\"og:description\" content=\"La madera sigue siendo una apuesta segura para los que buscan una combinaci\u00f3n especial en su vivienda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/\" \/>\n<meta property=\"og:site_name\" content=\"pedroriosehijos\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-26T10:40:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/07\/salon-abierto-al-dormitorio-pared-cristal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"asociados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"asociados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/\"},\"author\":{\"name\":\"asociados\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\"},\"headline\":\"El parquet, un tipo de suelo que no pierde popularidad\",\"datePublished\":\"2019-07-26T10:40:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/\"},\"wordCount\":316,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2019\\\/07\\\/salon-abierto-al-dormitorio-pared-cristal.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/\",\"name\":\"El parquet, un tipo de suelo que no pierde popularidad - pedroriosehijos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2019\\\/07\\\/salon-abierto-al-dormitorio-pared-cristal.jpg\",\"datePublished\":\"2019-07-26T10:40:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2019\\\/07\\\/salon-abierto-al-dormitorio-pared-cristal.jpg\",\"contentUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2019\\\/07\\\/salon-abierto-al-dormitorio-pared-cristal.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/07\\\/26\\\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El parquet, un tipo de suelo que no pierde popularidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#website\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/\",\"name\":\"pedroriosehijos\",\"description\":\"Otro sitio m\u00e1s de Asociados GrupoDCC3000\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\",\"name\":\"asociados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"caption\":\"asociados\"},\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/author\\\/asociados\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El parquet, un tipo de suelo que no pierde popularidad - pedroriosehijos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/","og_locale":"es_ES","og_type":"article","og_title":"El parquet, un tipo de suelo que no pierde popularidad - pedroriosehijos","og_description":"La madera sigue siendo una apuesta segura para los que buscan una combinaci\u00f3n especial en su vivienda.","og_url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/","og_site_name":"pedroriosehijos","article_published_time":"2019-07-26T10:40:18+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/07\/salon-abierto-al-dormitorio-pared-cristal.jpg","type":"image\/jpeg"}],"author":"asociados","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"asociados","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/#article","isPartOf":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/"},"author":{"name":"asociados","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119"},"headline":"El parquet, un tipo de suelo que no pierde popularidad","datePublished":"2019-07-26T10:40:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/"},"wordCount":316,"commentCount":0,"image":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/07\/salon-abierto-al-dormitorio-pared-cristal.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/","name":"El parquet, un tipo de suelo que no pierde popularidad - pedroriosehijos","isPartOf":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/#primaryimage"},"image":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/07\/salon-abierto-al-dormitorio-pared-cristal.jpg","datePublished":"2019-07-26T10:40:18+00:00","author":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119"},"breadcrumb":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/#primaryimage","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/07\/salon-abierto-al-dormitorio-pared-cristal.jpg","contentUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/07\/salon-abierto-al-dormitorio-pared-cristal.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/07\/26\/el-parquet-un-tipo-de-suelo-que-no-pierde-popularidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/"},{"@type":"ListItem","position":2,"name":"El parquet, un tipo de suelo que no pierde popularidad"}]},{"@type":"WebSite","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#website","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/","name":"pedroriosehijos","description":"Otro sitio m\u00e1s de Asociados GrupoDCC3000","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119","name":"asociados","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","caption":"asociados"},"url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/author\/asociados\/"}]}},"_links":{"self":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts\/1445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/comments?post=1445"}],"version-history":[{"count":0,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts\/1445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/media\/1398"}],"wp:attachment":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/media?parent=1445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/categories?post=1445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/tags?post=1445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}