{"id":1520,"date":"2020-08-29T20:26:00","date_gmt":"2020-08-29T20:26:00","guid":{"rendered":"https:\/\/www.grupodcc3000.com\/asociado\/?p=1520"},"modified":"2020-08-29T20:26:00","modified_gmt":"2020-08-29T20:26:00","slug":"reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina","status":"publish","type":"post","link":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/","title":{"rendered":"Reforma tu ba\u00f1o casi sin grandes obras con Cer\u00e1mica Extrafina"},"content":{"rendered":"<p><!--StartFragment--><\/p>\n\n<p class=\"wp-block-paragraph\">\u00bfEst\u00e1s pensando en renovar el estilo o la decoraci\u00f3n del cuarto de ba\u00f1o pero no quieres meterte en una obra? Te preguntar\u00e1s si hay alguna manera de reformar el ba\u00f1o sin hacer obras. Y en este art\u00edculo te presentamos una en la que se emplea cer\u00e1mica extrafina.<\/p>\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.grupodcc3000.com\/asociado\/wp-content\/uploads\/2019\/08\/reforma-tu-bano-sin-obras-con-ceramica-extrafina-Iceberg-Blanco-Mate-SlimRect_JEYiG-1024x512.jpg\" alt=\"\" class=\"wp-image-1513\" \/><\/figure>\n\n\n<p class=\"wp-block-paragraph\">\u00bfSabes por qu\u00e9 la cer\u00e1mica extrafina es la mejor opci\u00f3n para reformar un ba\u00f1o sin obras? Pues, muy f\u00e1cil, porque la cer\u00e1mica extrafina te permite sobre-alicatar, es decir reformar un ba\u00f1o sin quitar los azulejos que ya tenemos puestos, pero, adem\u00e1s, tiene todas las cualidades exclusivas de la cer\u00e1mica, entre las que destacan: <\/p>\n\n\n<ul class=\"wp-block-list\"><li><strong>Durabilidad<\/strong><\/li><li><strong>Resistencia<\/strong> <\/li><li><strong>Ign\u00edfuga<\/strong><\/li><li><strong>Funcionalidad<\/strong> <\/li><li><strong>F\u00e1cil Mantenimiento<\/strong> <\/li><li><strong>Sostenible<\/strong><\/li><li><strong>Ecol\u00f3gica<\/strong><\/li><\/ul>\n\n\n<p class=\"wp-block-paragraph\">La principal ventaja de la cer\u00e1mica extrafina es que permite el sobre-alicatado. Por tanto, podr\u00e1s colocar nuestros azulejos de cer\u00e1mica extrafina en el suelo de tu cuarto de ba\u00f1o sobre los azulejos existentes o cualquier otro tipo de material.&nbsp;<\/p>\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.grupodcc3000.com\/asociado\/wp-content\/uploads\/2019\/08\/reforma-tu-bano-sin-obras-con-ceramica-extrafina-Expression-Titanio-25x65-SlimRect_gfxYf-1024x512.jpg\" alt=\"\" class=\"wp-image-1514\" \/><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Te dejamos un peque\u00f1o v\u00eddeo sobre la cer\u00e1mica extrafina de nuestro proveedor Azulev:<\/p>\n\n\n<figure><\/figure>\n\n\n<p class=\"wp-block-paragraph\">El grupo <strong>Azulev<\/strong> es uno de nuestros proveedores de Referencia.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Nosotros pertenecemos a la Central de Compras de Almacenes de Materiales de Construcci\u00f3n <strong><a href=\"https:\/\/www.grupodcc3000.com\/proveedores.php\">GRUPO DCC3000<\/a><\/strong> a trav\u00e9s de la que podemos ofrecerte todo lo que necesites para tu obra o reforma al mejor precio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSabes por qu\u00e9 la cer\u00e1mica extrafina es la mejor opci\u00f3n para reformar un ba\u00f1o sin obras? Pues, muy f\u00e1cil, porque la cer\u00e1mica extrafina te permite sobre-alicatar, es decir reformar un ba\u00f1o sin quitar los azulejos que ya tenemos puestos, pero, adem\u00e1s, tiene todas las cualidades exclusivas de la cer\u00e1mica.<\/p>\n","protected":false},"author":4,"featured_media":2709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reforma tu ba\u00f1o casi sin grandes obras con Cer\u00e1mica Extrafina - pedroriosehijos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reforma tu ba\u00f1o casi sin grandes obras con Cer\u00e1mica Extrafina - pedroriosehijos\" \/>\n<meta property=\"og:description\" content=\"\u00bfSabes por qu\u00e9 la cer\u00e1mica extrafina es la mejor opci\u00f3n para reformar un ba\u00f1o sin obras? Pues, muy f\u00e1cil, porque la cer\u00e1mica extrafina te permite sobre-alicatar, es decir reformar un ba\u00f1o sin quitar los azulejos que ya tenemos puestos, pero, adem\u00e1s, tiene todas las cualidades exclusivas de la cer\u00e1mica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/\" \/>\n<meta property=\"og:site_name\" content=\"pedroriosehijos\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-29T20:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/08\/reforma-tu-bano-sin-obras-con-ceramica-extrafina-Iceberg-Blanco-Mate-SlimRect_JEYiG-1024x512-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"asociados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"asociados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/\"},\"author\":{\"name\":\"asociados\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\"},\"headline\":\"Reforma tu ba\u00f1o casi sin grandes obras con Cer\u00e1mica Extrafina\",\"datePublished\":\"2020-08-29T20:26:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/\"},\"wordCount\":244,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2020\\\/08\\\/reforma-tu-bano-sin-obras-con-ceramica-extrafina-Iceberg-Blanco-Mate-SlimRect_JEYiG-1024x512-1.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/\",\"name\":\"Reforma tu ba\u00f1o casi sin grandes obras con Cer\u00e1mica Extrafina - pedroriosehijos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2020\\\/08\\\/reforma-tu-bano-sin-obras-con-ceramica-extrafina-Iceberg-Blanco-Mate-SlimRect_JEYiG-1024x512-1.jpg\",\"datePublished\":\"2020-08-29T20:26:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2020\\\/08\\\/reforma-tu-bano-sin-obras-con-ceramica-extrafina-Iceberg-Blanco-Mate-SlimRect_JEYiG-1024x512-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2020\\\/08\\\/reforma-tu-bano-sin-obras-con-ceramica-extrafina-Iceberg-Blanco-Mate-SlimRect_JEYiG-1024x512-1.jpg\",\"width\":1024,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/08\\\/29\\\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reforma tu ba\u00f1o casi sin grandes obras con Cer\u00e1mica Extrafina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#website\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/\",\"name\":\"pedroriosehijos\",\"description\":\"Otro sitio m\u00e1s de Asociados GrupoDCC3000\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\",\"name\":\"asociados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"caption\":\"asociados\"},\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/author\\\/asociados\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reforma tu ba\u00f1o casi sin grandes obras con Cer\u00e1mica Extrafina - pedroriosehijos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/","og_locale":"es_ES","og_type":"article","og_title":"Reforma tu ba\u00f1o casi sin grandes obras con Cer\u00e1mica Extrafina - pedroriosehijos","og_description":"\u00bfSabes por qu\u00e9 la cer\u00e1mica extrafina es la mejor opci\u00f3n para reformar un ba\u00f1o sin obras? Pues, muy f\u00e1cil, porque la cer\u00e1mica extrafina te permite sobre-alicatar, es decir reformar un ba\u00f1o sin quitar los azulejos que ya tenemos puestos, pero, adem\u00e1s, tiene todas las cualidades exclusivas de la cer\u00e1mica.","og_url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/","og_site_name":"pedroriosehijos","article_published_time":"2020-08-29T20:26:00+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/08\/reforma-tu-bano-sin-obras-con-ceramica-extrafina-Iceberg-Blanco-Mate-SlimRect_JEYiG-1024x512-1.jpg","type":"image\/jpeg"}],"author":"asociados","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"asociados","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/#article","isPartOf":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/"},"author":{"name":"asociados","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119"},"headline":"Reforma tu ba\u00f1o casi sin grandes obras con Cer\u00e1mica Extrafina","datePublished":"2020-08-29T20:26:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/"},"wordCount":244,"commentCount":0,"image":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/08\/reforma-tu-bano-sin-obras-con-ceramica-extrafina-Iceberg-Blanco-Mate-SlimRect_JEYiG-1024x512-1.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/","name":"Reforma tu ba\u00f1o casi sin grandes obras con Cer\u00e1mica Extrafina - pedroriosehijos","isPartOf":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/#primaryimage"},"image":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/08\/reforma-tu-bano-sin-obras-con-ceramica-extrafina-Iceberg-Blanco-Mate-SlimRect_JEYiG-1024x512-1.jpg","datePublished":"2020-08-29T20:26:00+00:00","author":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119"},"breadcrumb":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/#primaryimage","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/08\/reforma-tu-bano-sin-obras-con-ceramica-extrafina-Iceberg-Blanco-Mate-SlimRect_JEYiG-1024x512-1.jpg","contentUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/08\/reforma-tu-bano-sin-obras-con-ceramica-extrafina-Iceberg-Blanco-Mate-SlimRect_JEYiG-1024x512-1.jpg","width":1024,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/08\/29\/reforma-tu-bano-casi-sin-grandes-obras-con-ceramica-extrafina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/"},{"@type":"ListItem","position":2,"name":"Reforma tu ba\u00f1o casi sin grandes obras con Cer\u00e1mica Extrafina"}]},{"@type":"WebSite","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#website","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/","name":"pedroriosehijos","description":"Otro sitio m\u00e1s de Asociados GrupoDCC3000","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119","name":"asociados","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","caption":"asociados"},"url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/author\/asociados\/"}]}},"_links":{"self":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts\/1520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/comments?post=1520"}],"version-history":[{"count":0,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts\/1520\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/media\/2709"}],"wp:attachment":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/media?parent=1520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/categories?post=1520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/tags?post=1520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}