{"id":1571,"date":"2019-08-14T13:00:54","date_gmt":"2019-08-14T13:00:54","guid":{"rendered":"https:\/\/www.grupodcc3000.com\/asociado\/?p=1571"},"modified":"2019-08-14T13:00:54","modified_gmt":"2019-08-14T13:00:54","slug":"conoceis-morcemcolor-epoxi-de-grupo-puma","status":"publish","type":"post","link":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/","title":{"rendered":"\u00bfConoc\u00e9is Morcemcolor Epoxi de Grupo Puma?"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Mortero epoxi bicomponente anti\u00e1cido, para la colocaci\u00f3n y el relleno de azulejos cer\u00e1micos y mosaicos con juntas de anchura comprendida entre 1 y 15 mm. Resistente a la exposici\u00f3n a los rayos UV y a la acci\u00f3n meteorol\u00f3gica y climatol\u00f3gica. Haz click aqu\u00ed y descubre su <a href=\"https:\/\/www.grupopuma.com\/services\/pdf\/5534\">ficha t\u00e9cnica<\/a>.<\/p><cite><a href=\"https:\/\/www.grupopuma.com\/es-ES\/productos\/ver\/morcemcolor-epoxi-es-es-1\">https:\/\/www.grupopuma.com\/es-ES\/productos\/ver\/morcemcolor-epoxi-es-es-1<\/a><\/cite><\/blockquote>\n\n\n<p class=\"wp-block-paragraph\">Os dejamos un v\u00eddeo explicativo de como se aplica para que os hag\u00e1is una idea de manera visual de lo potente que es este adhesivo. Avalado y certificado por Grupo DCC. Llevamos muchos a\u00f1os contando con Grupo Puma como proveedor oficial. Toda una garant\u00eda: <\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p><\/p>\n\n<p class=\"wp-block-paragraph\">En su <a href=\"https:\/\/www.grupopuma.com\/es-ES\/productos\/ver\/morcemcolor-epoxi-es-es-1\">web<\/a> detallan los soportes sobre los que trabajar, su modo de empleo y las caracter\u00edsticas y especificaciones t\u00e9cnica. <\/p>\n\n\n<p class=\"wp-block-paragraph\">Pregunta por este producto y otros productos de  @grupopuma  en nuestro establecimiento. <\/p>\n\n\n<p class=\"wp-block-paragraph\">Estamos adheridos a Grupo DCC3000 , Central de Compras de Almacenes de materiales de Construci\u00f3n. <strong>La fuerza y la ventaja de pertenecer a un grupo. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os dejamos un v\u00eddeo explicativo de como se aplica para que os hag\u00e1is una idea de manera visual de lo potente que es este adhesivo. Avalado y certificado por Grupo DCC. Llevamos muchos a\u00f1os contando con Grupo Puma como proveedor oficial. Toda una garant\u00eda:<\/p>\n","protected":false},"author":4,"featured_media":1573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfConoc\u00e9is Morcemcolor Epoxi de Grupo Puma? - pedroriosehijos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfConoc\u00e9is Morcemcolor Epoxi de Grupo Puma? - pedroriosehijos\" \/>\n<meta property=\"og:description\" content=\"Os dejamos un v\u00eddeo explicativo de como se aplica para que os hag\u00e1is una idea de manera visual de lo potente que es este adhesivo. Avalado y certificado por Grupo DCC. Llevamos muchos a\u00f1os contando con Grupo Puma como proveedor oficial. Toda una garant\u00eda:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/\" \/>\n<meta property=\"og:site_name\" content=\"pedroriosehijos\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-14T13:00:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/08\/Captura-de-pantalla-2019-08-13-a-las-11.15.12.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1346\" \/>\n\t<meta property=\"og:image:height\" content=\"1168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"asociados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"asociados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/\"},\"author\":{\"name\":\"asociados\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\"},\"headline\":\"\u00bfConoc\u00e9is Morcemcolor Epoxi de Grupo Puma?\",\"datePublished\":\"2019-08-14T13:00:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/\"},\"wordCount\":176,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2019\\\/08\\\/Captura-de-pantalla-2019-08-13-a-las-11.15.12.png\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/\",\"name\":\"\u00bfConoc\u00e9is Morcemcolor Epoxi de Grupo Puma? - pedroriosehijos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2019\\\/08\\\/Captura-de-pantalla-2019-08-13-a-las-11.15.12.png\",\"datePublished\":\"2019-08-14T13:00:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2019\\\/08\\\/Captura-de-pantalla-2019-08-13-a-las-11.15.12.png\",\"contentUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2019\\\/08\\\/Captura-de-pantalla-2019-08-13-a-las-11.15.12.png\",\"width\":1346,\"height\":1168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/08\\\/14\\\/conoceis-morcemcolor-epoxi-de-grupo-puma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfConoc\u00e9is Morcemcolor Epoxi de Grupo Puma?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#website\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/\",\"name\":\"pedroriosehijos\",\"description\":\"Otro sitio m\u00e1s de Asociados GrupoDCC3000\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\",\"name\":\"asociados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"caption\":\"asociados\"},\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/author\\\/asociados\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfConoc\u00e9is Morcemcolor Epoxi de Grupo Puma? - pedroriosehijos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfConoc\u00e9is Morcemcolor Epoxi de Grupo Puma? - pedroriosehijos","og_description":"Os dejamos un v\u00eddeo explicativo de como se aplica para que os hag\u00e1is una idea de manera visual de lo potente que es este adhesivo. Avalado y certificado por Grupo DCC. Llevamos muchos a\u00f1os contando con Grupo Puma como proveedor oficial. Toda una garant\u00eda:","og_url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/","og_site_name":"pedroriosehijos","article_published_time":"2019-08-14T13:00:54+00:00","og_image":[{"width":1346,"height":1168,"url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/08\/Captura-de-pantalla-2019-08-13-a-las-11.15.12.png","type":"image\/png"}],"author":"asociados","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"asociados","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/#article","isPartOf":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/"},"author":{"name":"asociados","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119"},"headline":"\u00bfConoc\u00e9is Morcemcolor Epoxi de Grupo Puma?","datePublished":"2019-08-14T13:00:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/"},"wordCount":176,"commentCount":0,"image":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/08\/Captura-de-pantalla-2019-08-13-a-las-11.15.12.png","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/","name":"\u00bfConoc\u00e9is Morcemcolor Epoxi de Grupo Puma? - pedroriosehijos","isPartOf":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/#primaryimage"},"image":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/08\/Captura-de-pantalla-2019-08-13-a-las-11.15.12.png","datePublished":"2019-08-14T13:00:54+00:00","author":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119"},"breadcrumb":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/#primaryimage","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/08\/Captura-de-pantalla-2019-08-13-a-las-11.15.12.png","contentUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/08\/Captura-de-pantalla-2019-08-13-a-las-11.15.12.png","width":1346,"height":1168},{"@type":"BreadcrumbList","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/08\/14\/conoceis-morcemcolor-epoxi-de-grupo-puma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/"},{"@type":"ListItem","position":2,"name":"\u00bfConoc\u00e9is Morcemcolor Epoxi de Grupo Puma?"}]},{"@type":"WebSite","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#website","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/","name":"pedroriosehijos","description":"Otro sitio m\u00e1s de Asociados GrupoDCC3000","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119","name":"asociados","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","caption":"asociados"},"url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/author\/asociados\/"}]}},"_links":{"self":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts\/1571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/comments?post=1571"}],"version-history":[{"count":0,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts\/1571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/media\/1573"}],"wp:attachment":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/media?parent=1571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/categories?post=1571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/tags?post=1571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}