{"id":1785,"date":"2019-10-03T09:04:55","date_gmt":"2019-10-03T09:04:55","guid":{"rendered":"https:\/\/www.grupodcc3000.com\/asociado\/blog\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/"},"modified":"2019-10-03T09:04:55","modified_gmt":"2019-10-03T09:04:55","slug":"serie-de-revestimientos-masai-de-valentia","status":"publish","type":"post","link":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/","title":{"rendered":"Serie de revestimientos Masai, de Valentia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00bfEst\u00e1s buscando un estilo original para renovar la soler\u00eda o revestir las paredes de tu vivienda? Te presentamos la Serie de revestimientos MASAI, de nuestro proveedor Valentia.<\/p>\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"770\" src=\"https:\/\/i0.wp.com\/www.grupodcc3000.com\/asociado\/wp-content\/uploads\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1.jpg?fit=1024%2C717&amp;ssl=1\" alt=\"\" class=\"wp-image-1780\" srcset=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1.jpg 1100w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1-300x210.jpg 300w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1-1024x717.jpg 1024w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1-768x538.jpg 768w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1-1080x756.jpg 1080w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1-980x686.jpg 980w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1-480x336.jpg 480w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/figure><\/div>\n\n\n<p class=\"wp-block-paragraph\">La serie Masai es un revestimiento formado por fragmentos de materiales y minerales con acabados de alta gama. Su peculiar estilo nos transporta al continente africano donde priman los colores naturales que se asemejan a la tierra, madera o minerales.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Si tu intenci\u00f3n es salirte de lo com\u00fan en lo que a pavimentos se refiere, sin duda la serie Masai es una apuesta segura que otorgar\u00e1 una identidad visual particular a tus estancias. <\/p>\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1100\" height=\"754\" src=\"https:\/\/i1.wp.com\/www.grupodcc3000.com\/asociado\/wp-content\/uploads\/2019\/10\/20X60-MASAI-MARENGO-BASES-1.jpg?fit=1024%2C702&amp;ssl=1\" alt=\"\" class=\"wp-image-1782\" srcset=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-MARENGO-BASES-1.jpg 1100w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-MARENGO-BASES-1-300x206.jpg 300w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-MARENGO-BASES-1-1024x702.jpg 1024w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-MARENGO-BASES-1-768x526.jpg 768w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-MARENGO-BASES-1-1080x740.jpg 1080w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-MARENGO-BASES-1-980x672.jpg 980w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-MARENGO-BASES-1-480x329.jpg 480w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, Valentia te ofrece una gran variedad de estilos dentro de la serie, desde el Masai Marfil, el Masai Nuez o el Masai Miel. Asimismo, tambi\u00e9n tienes la opci\u00f3n de elegir colores m\u00e1s neutros como el blanco o el marengo. <\/p>\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1760\" height=\"1300\" src=\"https:\/\/i1.wp.com\/www.grupodcc3000.com\/asociado\/wp-content\/uploads\/2019\/10\/Captura-de-pantalla-2019-10-03-a-las-11.03.07.jpg?fit=1024%2C756&amp;ssl=1\" alt=\"\" class=\"wp-image-1783\" srcset=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/Captura-de-pantalla-2019-10-03-a-las-11.03.07.jpg 1760w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/Captura-de-pantalla-2019-10-03-a-las-11.03.07-300x222.jpg 300w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/Captura-de-pantalla-2019-10-03-a-las-11.03.07-1024x756.jpg 1024w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/Captura-de-pantalla-2019-10-03-a-las-11.03.07-768x567.jpg 768w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/Captura-de-pantalla-2019-10-03-a-las-11.03.07-1536x1135.jpg 1536w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/Captura-de-pantalla-2019-10-03-a-las-11.03.07-1080x798.jpg 1080w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/Captura-de-pantalla-2019-10-03-a-las-11.03.07-1280x945.jpg 1280w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/Captura-de-pantalla-2019-10-03-a-las-11.03.07-980x724.jpg 980w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/Captura-de-pantalla-2019-10-03-a-las-11.03.07-480x355.jpg 480w\" sizes=\"(max-width: 1760px) 100vw, 1760px\" \/><\/figure>\n\n\n<p class=\"wp-block-paragraph\">No te arrepentir\u00e1s de elegir esta serie para tu casa y adaptar los revestimientos a tus gustos personales.  <\/p>\n\n\n<p class=\"wp-block-paragraph\">Todo esto y m\u00e1s podr\u00e1s encontrarlo en nuestro almac\u00e9n y\/o exposici\u00f3n. No dudes en consultarnos, estaremos encantados de atenterte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfEst\u00e1s buscando un estilo original para renovar la soler\u00eda o revestir las paredes de tu vivienda? Te presentamos la Serie de revestimientos MASAI, de nuestro proveedor Valentia.<\/p>\n","protected":false},"author":4,"featured_media":1786,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Serie de revestimientos Masai, de Valentia - pedroriosehijos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serie de revestimientos Masai, de Valentia - pedroriosehijos\" \/>\n<meta property=\"og:description\" content=\"\u00bfEst\u00e1s buscando un estilo original para renovar la soler\u00eda o revestir las paredes de tu vivienda? Te presentamos la Serie de revestimientos MASAI, de nuestro proveedor Valentia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/\" \/>\n<meta property=\"og:site_name\" content=\"pedroriosehijos\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-03T09:04:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"770\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"asociados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"asociados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/\"},\"author\":{\"name\":\"asociados\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\"},\"headline\":\"Serie de revestimientos Masai, de Valentia\",\"datePublished\":\"2019-10-03T09:04:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/\"},\"wordCount\":197,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2019\\\/10\\\/20X60-MASAI-NUEZ-BOMA-X-1-1.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/\",\"name\":\"Serie de revestimientos Masai, de Valentia - pedroriosehijos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2019\\\/10\\\/20X60-MASAI-NUEZ-BOMA-X-1-1.jpg\",\"datePublished\":\"2019-10-03T09:04:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2019\\\/10\\\/20X60-MASAI-NUEZ-BOMA-X-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2019\\\/10\\\/20X60-MASAI-NUEZ-BOMA-X-1-1.jpg\",\"width\":1100,\"height\":770},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2019\\\/10\\\/03\\\/serie-de-revestimientos-masai-de-valentia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serie de revestimientos Masai, de Valentia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#website\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/\",\"name\":\"pedroriosehijos\",\"description\":\"Otro sitio m\u00e1s de Asociados GrupoDCC3000\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\",\"name\":\"asociados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"caption\":\"asociados\"},\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/author\\\/asociados\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serie de revestimientos Masai, de Valentia - pedroriosehijos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/","og_locale":"es_ES","og_type":"article","og_title":"Serie de revestimientos Masai, de Valentia - pedroriosehijos","og_description":"\u00bfEst\u00e1s buscando un estilo original para renovar la soler\u00eda o revestir las paredes de tu vivienda? Te presentamos la Serie de revestimientos MASAI, de nuestro proveedor Valentia.","og_url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/","og_site_name":"pedroriosehijos","article_published_time":"2019-10-03T09:04:55+00:00","og_image":[{"width":1100,"height":770,"url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1-1.jpg","type":"image\/jpeg"}],"author":"asociados","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"asociados","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/#article","isPartOf":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/"},"author":{"name":"asociados","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119"},"headline":"Serie de revestimientos Masai, de Valentia","datePublished":"2019-10-03T09:04:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/"},"wordCount":197,"commentCount":0,"image":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1-1.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/","name":"Serie de revestimientos Masai, de Valentia - pedroriosehijos","isPartOf":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/#primaryimage"},"image":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1-1.jpg","datePublished":"2019-10-03T09:04:55+00:00","author":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119"},"breadcrumb":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/#primaryimage","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1-1.jpg","contentUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2019\/10\/20X60-MASAI-NUEZ-BOMA-X-1-1.jpg","width":1100,"height":770},{"@type":"BreadcrumbList","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2019\/10\/03\/serie-de-revestimientos-masai-de-valentia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/"},{"@type":"ListItem","position":2,"name":"Serie de revestimientos Masai, de Valentia"}]},{"@type":"WebSite","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#website","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/","name":"pedroriosehijos","description":"Otro sitio m\u00e1s de Asociados GrupoDCC3000","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119","name":"asociados","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","caption":"asociados"},"url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/author\/asociados\/"}]}},"_links":{"self":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts\/1785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/comments?post=1785"}],"version-history":[{"count":0,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts\/1785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/media\/1786"}],"wp:attachment":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/media?parent=1785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/categories?post=1785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/tags?post=1785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}