{"id":2283,"date":"2020-01-22T12:55:21","date_gmt":"2020-01-22T12:55:21","guid":{"rendered":"https:\/\/www.grupodcc3000.com\/asociado\/blog\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/"},"modified":"2020-01-22T12:55:21","modified_gmt":"2020-01-22T12:55:21","slug":"serie-tibet-de-struket-porcelanico","status":"publish","type":"post","link":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/","title":{"rendered":"Serie Tibet de Struket Porcel\u00e1nico"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Actualmente, el\u00a0<strong>gres porcel\u00e1nico<\/strong>\u00a0se est\u00e1 volviendo toda una\u00a0<strong>tendencia en interiorismo<\/strong>, es por ello que hoy hablaremos de la Serie Tibet, una apuesta por el minimalismo que cambiar\u00e1 la percepci\u00f3n de tu vivienda. <\/h2>\n\n\n<p class=\"wp-block-paragraph\">Como ya vimos en anteriores publicaciones, el gres porcel\u00e1nico est\u00e1 fabricado a partir de cer\u00e1mica prensada y cocida, lo que incrementa su resistencia y lo convierte en un material muy atractivo para soler\u00eda o zonas muy concurridas.<\/p>\n\n\n<p class=\"wp-block-paragraph\">En concreto, la Serie Tibet, adem\u00e1s de brindarnos muchas otras ventajas, est\u00e1 pensada para aportar una armon\u00eda caracter\u00edstica a tu hogar. Nuestro proveedor Strucker Porcel\u00e1nico nos ofrece dos gamas de colores para adaptarlas a nuestra decoraci\u00f3n propia:<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1726\" height=\"942\" src=\"https:\/\/i0.wp.com\/www.grupodcc3000.com\/asociado\/wp-content\/uploads\/2020\/01\/Captura-de-pantalla-2020-01-22-a-las-13.52.32.png?fit=1024%2C559&amp;ssl=1\" alt=\"\" class=\"wp-image-2280\" srcset=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/Captura-de-pantalla-2020-01-22-a-las-13.52.32.png 1726w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/Captura-de-pantalla-2020-01-22-a-las-13.52.32-300x164.png 300w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/Captura-de-pantalla-2020-01-22-a-las-13.52.32-1024x559.png 1024w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/Captura-de-pantalla-2020-01-22-a-las-13.52.32-768x419.png 768w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/Captura-de-pantalla-2020-01-22-a-las-13.52.32-1536x838.png 1536w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/Captura-de-pantalla-2020-01-22-a-las-13.52.32-1080x589.png 1080w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/Captura-de-pantalla-2020-01-22-a-las-13.52.32-1280x699.png 1280w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/Captura-de-pantalla-2020-01-22-a-las-13.52.32-980x535.png 980w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/Captura-de-pantalla-2020-01-22-a-las-13.52.32-480x262.png 480w\" sizes=\"(max-width: 1726px) 100vw, 1726px\" \/><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Por un lado, encontramos la Serie Tibet <strong>\u00abSand\u00bb<\/strong> que nos brinda una est\u00e9tica lineal basada en el color de las playas m\u00e1s blancas. Esta gama es perfecta para combinar en espacios claros donde se pretende guardar una armon\u00eda basada en la iluminaci\u00f3n. Pero tambi\u00e9n queda a la perfecci\u00f3n en contraste con tonos oscuros, lo que nos aporta un claro elemento disruptivo.<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"900\" src=\"https:\/\/i0.wp.com\/www.grupodcc3000.com\/asociado\/wp-content\/uploads\/2020\/01\/tibet_sand_1.jpg?fit=1024%2C512&amp;ssl=1\" alt=\"\" class=\"wp-image-2278\" srcset=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_sand_1.jpg 1800w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_sand_1-300x150.jpg 300w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_sand_1-1024x512.jpg 1024w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_sand_1-768x384.jpg 768w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_sand_1-1536x768.jpg 1536w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_sand_1-1080x540.jpg 1080w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_sand_1-1280x640.jpg 1280w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_sand_1-980x490.jpg 980w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_sand_1-480x240.jpg 480w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><figcaption><em>Gama Sand<\/em><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, tenemos la gama <strong>\u00abGrey\u00bb<\/strong> que encaja a la perfecci\u00f3n en decoraciones modernas como el estilo n\u00f3rdico en el que priman los elementos en tonalidades blancas, negras e incluso grises; o en las decoraciones industriales, caracterizadas por los elementos metalizados.<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"900\" src=\"https:\/\/i0.wp.com\/www.grupodcc3000.com\/asociado\/wp-content\/uploads\/2020\/01\/tibet_grey_1.jpg?fit=1024%2C512&amp;ssl=1\" alt=\"\" class=\"wp-image-2279\" srcset=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_grey_1.jpg 1800w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_grey_1-300x150.jpg 300w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_grey_1-1024x512.jpg 1024w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_grey_1-768x384.jpg 768w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_grey_1-1536x768.jpg 1536w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_grey_1-1080x540.jpg 1080w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_grey_1-1280x640.jpg 1280w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_grey_1-980x490.jpg 980w, https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet_grey_1-480x240.jpg 480w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><figcaption><em>Gama Grey<\/em><\/figcaption><\/figure>\n\n\n<p class=\"wp-block-paragraph\">Si est\u00e1s buscando cambiar la decoraci\u00f3n de tu casa e introducir elementos minimalistas, la Serie TIBET es tu elecci\u00f3n ideal.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Todo esto y m\u00e1s podr\u00e1s encontrarlo en nuestro almac\u00e9n y\/o exposici\u00f3n. No dudes en consultarnos, estaremos encantados de atenderte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Actualmente, el gres porcel\u00e1nico se est\u00e1 volviendo toda una tendencia en interiorismo, es por ello que hoy hablaremos de la Serie Tibet, una apuesta por el minimalismo que cambiar\u00e1 la percepci\u00f3n de tu vivienda. <\/p>\n","protected":false},"author":4,"featured_media":2284,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Serie Tibet de Struket Porcel\u00e1nico - pedroriosehijos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serie Tibet de Struket Porcel\u00e1nico - pedroriosehijos\" \/>\n<meta property=\"og:description\" content=\"Actualmente, el gres porcel\u00e1nico se est\u00e1 volviendo toda una tendencia en interiorismo, es por ello que hoy hablaremos de la Serie Tibet, una apuesta por el minimalismo que cambiar\u00e1 la percepci\u00f3n de tu vivienda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/\" \/>\n<meta property=\"og:site_name\" content=\"pedroriosehijos\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-22T12:55:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1890\" \/>\n\t<meta property=\"og:image:height\" content=\"874\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"asociados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"asociados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/\"},\"author\":{\"name\":\"asociados\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\"},\"headline\":\"Serie Tibet de Struket Porcel\u00e1nico\",\"datePublished\":\"2020-01-22T12:55:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/\"},\"wordCount\":286,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2020\\\/01\\\/tibet-1.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/\",\"name\":\"Serie Tibet de Struket Porcel\u00e1nico - pedroriosehijos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2020\\\/01\\\/tibet-1.jpg\",\"datePublished\":\"2020-01-22T12:55:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2020\\\/01\\\/tibet-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/wp-content\\\/uploads\\\/sites\\\/179\\\/2020\\\/01\\\/tibet-1.jpg\",\"width\":1890,\"height\":874},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/2020\\\/01\\\/22\\\/serie-tibet-de-struket-porcelanico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serie Tibet de Struket Porcel\u00e1nico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#website\",\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/\",\"name\":\"pedroriosehijos\",\"description\":\"Otro sitio m\u00e1s de Asociados GrupoDCC3000\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/#\\\/schema\\\/person\\\/2b64f2e2bd240c328e3e8d0df54cd119\",\"name\":\"asociados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g\",\"caption\":\"asociados\"},\"url\":\"https:\\\/\\\/www.grupodcc3000.com\\\/asociado\\\/pedroriosehijos\\\/author\\\/asociados\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serie Tibet de Struket Porcel\u00e1nico - pedroriosehijos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/","og_locale":"es_ES","og_type":"article","og_title":"Serie Tibet de Struket Porcel\u00e1nico - pedroriosehijos","og_description":"Actualmente, el gres porcel\u00e1nico se est\u00e1 volviendo toda una tendencia en interiorismo, es por ello que hoy hablaremos de la Serie Tibet, una apuesta por el minimalismo que cambiar\u00e1 la percepci\u00f3n de tu vivienda.","og_url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/","og_site_name":"pedroriosehijos","article_published_time":"2020-01-22T12:55:21+00:00","og_image":[{"width":1890,"height":874,"url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet-1.jpg","type":"image\/jpeg"}],"author":"asociados","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"asociados","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/#article","isPartOf":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/"},"author":{"name":"asociados","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119"},"headline":"Serie Tibet de Struket Porcel\u00e1nico","datePublished":"2020-01-22T12:55:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/"},"wordCount":286,"commentCount":0,"image":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet-1.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/","name":"Serie Tibet de Struket Porcel\u00e1nico - pedroriosehijos","isPartOf":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/#primaryimage"},"image":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet-1.jpg","datePublished":"2020-01-22T12:55:21+00:00","author":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119"},"breadcrumb":{"@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/#primaryimage","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet-1.jpg","contentUrl":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-content\/uploads\/sites\/179\/2020\/01\/tibet-1.jpg","width":1890,"height":874},{"@type":"BreadcrumbList","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/2020\/01\/22\/serie-tibet-de-struket-porcelanico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/"},{"@type":"ListItem","position":2,"name":"Serie Tibet de Struket Porcel\u00e1nico"}]},{"@type":"WebSite","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#website","url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/","name":"pedroriosehijos","description":"Otro sitio m\u00e1s de Asociados GrupoDCC3000","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/#\/schema\/person\/2b64f2e2bd240c328e3e8d0df54cd119","name":"asociados","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b41fd62627be1e31dd70c283f3c5188b54fd100fda2f47adaaedb335e881254?s=96&d=mm&r=g","caption":"asociados"},"url":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/author\/asociados\/"}]}},"_links":{"self":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts\/2283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/comments?post=2283"}],"version-history":[{"count":0,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/posts\/2283\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/media\/2284"}],"wp:attachment":[{"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/media?parent=2283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/categories?post=2283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grupodcc3000.com\/asociado\/pedroriosehijos\/wp-json\/wp\/v2\/tags?post=2283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}